{"id":8111,"date":"2023-05-19T10:50:52","date_gmt":"2023-05-19T08:50:52","guid":{"rendered":"https:\/\/rigazoo.lv\/?post_type=animal&#038;p=8111"},"modified":"2023-07-25T14:15:14","modified_gmt":"2023-07-25T12:15:14","slug":"llama","status":"publish","type":"animal","link":"https:\/\/rigazoo.lv\/en\/animals\/llama\/","title":{"rendered":"Llama"},"content":{"rendered":"\n<p>Llama is a domesticated species, originated 4000\u20136000 years ago in Peru, Central Andes. Its wild ancestor is Guanaco (<em>Lama guanicoe<\/em>).<\/p>\n\n\n\n<p><strong>Taxonomy<\/strong><\/p>\n\n\n\n<p>\u25a0 Phylum Chordata \u2013 chordates<br>\u25a0 Class Mammalia \u2013 mammals<br>\u25a0 Order Artiodactyla \u2013 even-toed ungulates<br>\u25a0 Family Camelidae \u2013 camelids<br>\u25a0 Species&nbsp;<em>Lama glama<\/em>&nbsp;\u2013 Llama<\/p>\n","protected":false},"featured_media":6141,"template":"","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"animal-category":[38,33],"animal-filter-1":[],"animal-filter-2":[],"class_list":["post-8111","animal","type-animal","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Llama - Zoo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rigazoo.lv\/en\/animals\/llama\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Llama - Zoo\" \/>\n<meta property=\"og:description\" content=\"Llama is a domesticated species, originated 4000\u20136000 years ago in Peru, Central Andes. Its wild ancestor is Guanaco (Lama guanicoe). Taxonomy \u25a0 Phylum Chordata \u2013 chordates\u25a0 Class Mammalia \u2013 mammals\u25a0 Order Artiodactyla \u2013 even-toed ungulates\u25a0 Family Camelidae \u2013 camelids\u25a0 Species&nbsp;Lama glama&nbsp;\u2013 Llama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rigazoo.lv\/en\/animals\/llama\/\" \/>\n<meta property=\"og:site_name\" content=\"Zoo\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T12:15:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rigazoo.lv\/wp-content\/uploads\/2023\/05\/majas-lama-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/animals\\\/llama\\\/\",\"url\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/animals\\\/llama\\\/\",\"name\":\"Llama - Zoo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/animals\\\/llama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/animals\\\/llama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rigazoo.lv\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/majas-lama-2.jpeg\",\"datePublished\":\"2023-05-19T08:50:52+00:00\",\"dateModified\":\"2023-07-25T12:15:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/animals\\\/llama\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rigazoo.lv\\\/en\\\/animals\\\/llama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/animals\\\/llama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rigazoo.lv\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/majas-lama-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/rigazoo.lv\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/majas-lama-2.jpeg\",\"width\":1440,\"height\":1080,\"caption\":\"Female Llama with a cria at the age of 1 month in C\u012bru\u013ci. \u2013 Photo: El\u012bna Gulbe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/animals\\\/llama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"S\u0101kums\",\"item\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animals\",\"item\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/animals\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Llama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/\",\"name\":\"Zoo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rigazoo.lv\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Llama - Zoo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rigazoo.lv\/en\/animals\/llama\/","og_locale":"en_US","og_type":"article","og_title":"Llama - Zoo","og_description":"Llama is a domesticated species, originated 4000\u20136000 years ago in Peru, Central Andes. Its wild ancestor is Guanaco (Lama guanicoe). Taxonomy \u25a0 Phylum Chordata \u2013 chordates\u25a0 Class Mammalia \u2013 mammals\u25a0 Order Artiodactyla \u2013 even-toed ungulates\u25a0 Family Camelidae \u2013 camelids\u25a0 Species&nbsp;Lama glama&nbsp;\u2013 Llama","og_url":"https:\/\/rigazoo.lv\/en\/animals\/llama\/","og_site_name":"Zoo","article_modified_time":"2023-07-25T12:15:14+00:00","og_image":[{"width":1440,"height":1080,"url":"https:\/\/rigazoo.lv\/wp-content\/uploads\/2023\/05\/majas-lama-2.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rigazoo.lv\/en\/animals\/llama\/","url":"https:\/\/rigazoo.lv\/en\/animals\/llama\/","name":"Llama - Zoo","isPartOf":{"@id":"https:\/\/rigazoo.lv\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rigazoo.lv\/en\/animals\/llama\/#primaryimage"},"image":{"@id":"https:\/\/rigazoo.lv\/en\/animals\/llama\/#primaryimage"},"thumbnailUrl":"https:\/\/rigazoo.lv\/wp-content\/uploads\/2023\/05\/majas-lama-2.jpeg","datePublished":"2023-05-19T08:50:52+00:00","dateModified":"2023-07-25T12:15:14+00:00","breadcrumb":{"@id":"https:\/\/rigazoo.lv\/en\/animals\/llama\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rigazoo.lv\/en\/animals\/llama\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/rigazoo.lv\/en\/animals\/llama\/#primaryimage","url":"https:\/\/rigazoo.lv\/wp-content\/uploads\/2023\/05\/majas-lama-2.jpeg","contentUrl":"https:\/\/rigazoo.lv\/wp-content\/uploads\/2023\/05\/majas-lama-2.jpeg","width":1440,"height":1080,"caption":"Female Llama with a cria at the age of 1 month in C\u012bru\u013ci. \u2013 Photo: El\u012bna Gulbe"},{"@type":"BreadcrumbList","@id":"https:\/\/rigazoo.lv\/en\/animals\/llama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"S\u0101kums","item":"https:\/\/rigazoo.lv\/en\/"},{"@type":"ListItem","position":2,"name":"Animals","item":"https:\/\/rigazoo.lv\/en\/animals\/"},{"@type":"ListItem","position":3,"name":"Llama"}]},{"@type":"WebSite","@id":"https:\/\/rigazoo.lv\/en\/#website","url":"https:\/\/rigazoo.lv\/en\/","name":"Zoo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rigazoo.lv\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/rigazoo.lv\/en\/wp-json\/wp\/v2\/animal\/8111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rigazoo.lv\/en\/wp-json\/wp\/v2\/animal"}],"about":[{"href":"https:\/\/rigazoo.lv\/en\/wp-json\/wp\/v2\/types\/animal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rigazoo.lv\/en\/wp-json\/wp\/v2\/media\/6141"}],"wp:attachment":[{"href":"https:\/\/rigazoo.lv\/en\/wp-json\/wp\/v2\/media?parent=8111"}],"wp:term":[{"taxonomy":"animal-category","embeddable":true,"href":"https:\/\/rigazoo.lv\/en\/wp-json\/wp\/v2\/animal-category?post=8111"},{"taxonomy":"animal-filter-1","embeddable":true,"href":"https:\/\/rigazoo.lv\/en\/wp-json\/wp\/v2\/animal-filter-1?post=8111"},{"taxonomy":"animal-filter-2","embeddable":true,"href":"https:\/\/rigazoo.lv\/en\/wp-json\/wp\/v2\/animal-filter-2?post=8111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}